{"id":9096,"date":"2022-09-20T22:50:00","date_gmt":"2022-09-20T20:50:00","guid":{"rendered":"https:\/\/phspot.ch\/blog\/?p=9096"},"modified":"2022-10-09T23:22:31","modified_gmt":"2022-10-09T21:22:31","slug":"vacances-glisses","status":"publish","type":"post","link":"https:\/\/phspot.ch\/blog\/index.php\/2022\/09\/20\/vacances-glisses\/","title":{"rendered":"Vacances Glisses"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.17.6&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.17.6&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.17.6&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_gallery gallery_ids=&#8221;9101,9102,9103,9104,9105,9106,9107,9108,9109,9110,9111,9135,9136,9133,9134,9112,9113,9114,9115,9116,9117,9118,9119,9120,9121,9122,9123,9126,9124,9125&#8243; show_title_and_caption=&#8221;off&#8221; show_pagination=&#8221;off&#8221; _builder_version=&#8221;4.17.6&#8243; _module_preset=&#8221;default&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;][\/et_pb_gallery][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8230;<\/p>\n","protected":false},"author":1,"featured_media":9098,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[3,5,21],"tags":[],"class_list":["post-9096","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bike","category-france","category-windsurf"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/phspot.ch\/blog\/wp-content\/uploads\/2022\/10\/20220916_134648-scaled.jpg","_links":{"self":[{"href":"https:\/\/phspot.ch\/blog\/index.php\/wp-json\/wp\/v2\/posts\/9096","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/phspot.ch\/blog\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/phspot.ch\/blog\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/phspot.ch\/blog\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/phspot.ch\/blog\/index.php\/wp-json\/wp\/v2\/comments?post=9096"}],"version-history":[{"count":3,"href":"https:\/\/phspot.ch\/blog\/index.php\/wp-json\/wp\/v2\/posts\/9096\/revisions"}],"predecessor-version":[{"id":9138,"href":"https:\/\/phspot.ch\/blog\/index.php\/wp-json\/wp\/v2\/posts\/9096\/revisions\/9138"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/phspot.ch\/blog\/index.php\/wp-json\/wp\/v2\/media\/9098"}],"wp:attachment":[{"href":"https:\/\/phspot.ch\/blog\/index.php\/wp-json\/wp\/v2\/media?parent=9096"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/phspot.ch\/blog\/index.php\/wp-json\/wp\/v2\/categories?post=9096"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/phspot.ch\/blog\/index.php\/wp-json\/wp\/v2\/tags?post=9096"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}